{"id":53291,"date":"2026-03-26T12:55:32","date_gmt":"2026-03-26T16:55:32","guid":{"rendered":"\/a-propos-de-bravenly\/"},"modified":"2026-06-30T14:54:26","modified_gmt":"2026-06-30T18:54:26","slug":"about-bravenly","status":"publish","type":"page","link":"\/frca\/about-bravenly\/","title":{"rendered":"About Bravenly"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(34,34,34,0) 0%|rgba(33,15,15,0.45) 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2026\/02\/288A0221.jpg\u00a0\u00bb min_height=\u00a0\u00bb228px\u00a0\u00bb custom_padding=\u00a0\u00bb90px||90px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-1f9b0bb3-481a-49f1-9fe6-999fc3c3182b%22:%91%22background_color_gradient_stops%22%93}\u00a0\u00bb][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb111.4px\u00a0\u00bb custom_margin=\u00a0\u00bb|auto|-9px|auto||\u00a0\u00bb custom_padding=\u00a0\u00bb||2px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbb9f16d62-6e1a-493e-befd-f1613ea66937&Prime; text_text_color=\u00a0\u00bbgcid-primary-color\u00a0\u00bb header_font=\u00a0\u00bbTenor Sans||||||||\u00a0\u00bb header_3_font=\u00a0\u00bbMontserrat|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb40px\u00a0\u00bb custom_margin=\u00a0\u00bb||10px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-primary-color%22:%91%22text_text_color%22%93}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">L\u2019HISTOIRE DE BRAVENLY<\/h3>\n<div style=\"width: 140px; height: 2px; background: #55876a; margin: 10px auto 25px;\"><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|1px||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.5em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p data-start=\"200\" data-end=\"721\">Bravenly Global est n\u00e9 d\u2019un r\u00eave. Celui de construire quelque chose de v\u00e9ritablement sp\u00e9cial et d\u2019offrir des produits incroyables \u00e0 ses clients. Les fondateurs de Bravenly ont \u00e0 c\u0153ur les gens, la famille et l\u2019entraide, tout ceci centr\u00e9 sur des croyances profondes sur l\u2019engagement envers l\u2019excellence dans tout ce qu\u2019ils entreprennent. Cette croyance et cette qu\u00eate d&rsquo;excellence se refl\u00e8tent dans leur fa\u00e7on d\u2019\u00e9lever leurs cinq enfants, de donner g\u00e9n\u00e9reusement, d\u2019aider la communaut\u00e9 avec humilit\u00e9 et de faire des affaires avec honn\u00eatet\u00e9 et sinc\u00e9rit\u00e9.  <\/p>\n<p data-start=\"723\" data-end=\"1592\">La PDG et cofondatrice de Bravenly, Aspen Emry, a commenc\u00e9 son parcours dans le domaine de la sant\u00e9 et du bien-\u00eatre il y a plus de 20 ans. Elle croit que donner la priorit\u00e9 aux gens est la base du succ\u00e8s. Elle et son mari, Brent, Directeur des op\u00e9rations de Bravenly, ont d\u00e9j\u00e0 vu d\u2019innombrables vies chang\u00e9es gr\u00e2ce \u00e0 Bravenly, autant par les r\u00e9sultats significatifs des produits que par les magnifiques relations qui se sont cr\u00e9\u00e9es en chemin. En 2020, ils se sont lanc\u00e9s avec une vision et une mission claires, de lancer Bravenly Global, l\u2019entreprise de leurs r\u00eaves.    <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.5em\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb|-19px||||\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p data-start=\"132\" data-end=\"614\">Ils sont pass\u00e9s massivement \u00e0 l\u2019action pour donner vie \u00e0 cette vision. Chez Bravenly, vous trouverez une gamme sup\u00e9rieure de produits destin\u00e9s \u00e0 un mode de vie sain, ainsi qu\u2019une communaut\u00e9 incroyable qui appr\u00e9cie autant les r\u00e9sultats de ces produits que les relations authentiques qui s\u2019y cr\u00e9ent. Et surtout, la transparence, la sinc\u00e9rit\u00e9, l\u2019humilit\u00e9, la croyance et le c\u0153ur font partie int\u00e9grante de tout ce que nous faisons. Chez Bravenly, vous comptez, vous \u00eates valoris\u00e9 et appr\u00e9ci\u00e9.   <\/p>\n<p data-start=\"616\" data-end=\"937\">Chez Bravenly, vous comptez pour nous. Que vous nous rejoigniez en tant que partenaire de marque, affili\u00e9 client VIP ou tout autre titre, nous vous accordons toute notre attention et notre reconnaissance. Nous sommes honor\u00e9s de vous accompagner gr\u00e2ce \u00e0 un encadrement, une formation et un mentorat continus, en vous soutenant avec bienveillance et avec la volont\u00e9 sinc\u00e8re d\u2019aller toujours plus loin dans tout ce que nous faisons.  <\/p>\n<p data-start=\"939\" data-end=\"1349\">Nos trois piliers \u2014Courage, Int\u00e9grit\u00e9, et Impact\u2014 repr\u00e9sentent qui nous sommes en tant qu\u2019entreprise et guident chacune de nos d\u00e9cisions. Unissons-nous et rappelons-nous que nous sommes plus forts ensemble. Bravenly, c\u2019est bien plus qu\u2019une gamme de produits exceptionnelle. Bravenly, c\u2019est une famille.    <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(255,255,255,0.9)\u00a0\u00bb min_height=\u00a0\u00bb184px\u00a0\u00bb custom_margin=\u00a0\u00bb0px|auto|16px|auto|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb40px|30px|81px|30px|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb40px|30px|30px|30px|false|false\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||30px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bb\/wp-content\/uploads\/2020\/12\/9-1.png\u00a0\u00bb title_text=\u00a0\u00bb9&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb130px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb|0px|||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#507f64&Prime; text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_font=\u00a0\u00bbTenor Sans||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#507f64&Prime; header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb|0px|||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\">COURAGE<\/h1>\n<p style=\"text-align: center;\">Soyez assez audacieux pour vous d\u00e9marquer par votre passion et votre d\u00e9termination.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bb\/wp-content\/uploads\/2020\/12\/10.png\u00a0\u00bb title_text=\u00a0\u00bb10&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb130px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#507f64&Prime; text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_font=\u00a0\u00bbTenor Sans||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#507f64&Prime; header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\">INT\u00c9GRIT\u00c9<\/h1>\n<p style=\"text-align: center;\">S\u2019engager \u00e0 faire preuve d\u2019honn\u00eatet\u00e9, d\u2019humilit\u00e9 et de coh\u00e9rence dans tout ce que nous faisons.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bb\/wp-content\/uploads\/2020\/12\/11.png\u00a0\u00bb title_text=\u00a0\u00bb11&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb130px\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#507f64&Prime; text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_font=\u00a0\u00bbTenor Sans||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#507f64&Prime; header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\">IMPACT<\/h1>\n<p style=\"text-align: center;\">Cr\u00e9er un puissant effet d&rsquo;entra\u00eenement au changement.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbFeature\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbb9f16d62-6e1a-493e-befd-f1613ea66937&Prime; header_font=\u00a0\u00bbTenor Sans||||||||\u00a0\u00bb header_3_font=\u00a0\u00bbMontserrat|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb40px\u00a0\u00bb custom_margin=\u00a0\u00bb||10px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">D\u00c9COUVREZ LA FAMILLE EMRY<\/h3>\n<div style=\"width: 140px; height: 2px; background: #55876a; margin: 10px auto 25px;\"><\/div>\n<p>[\/et_pb_text][et_pb_blurb image=\u00a0\u00bb\/wp-content\/uploads\/2024\/05\/IMG_2971.jpeg\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font_size=\u00a0\u00bb40px\u00a0\u00bb body_font=\u00a0\u00bbLato||||||||\u00a0\u00bb body_text_color=\u00a0\u00bb#000000&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb body_line_height=\u00a0\u00bb1.5em\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019HISTOIRE DE BRAVENLY Bravenly Global est n\u00e9 d\u2019un r\u00eave. Celui de construire quelque chose de v\u00e9ritablement sp\u00e9cial et d\u2019offrir des produits incroyables \u00e0 ses clients. Les fondateurs de Bravenly ont \u00e0 c\u0153ur les gens, la famille et l\u2019entraide, tout ceci centr\u00e9 sur des croyances profondes sur l\u2019engagement envers l\u2019excellence dans tout ce qu\u2019ils entreprennent. Cette [&hellip;]<\/p>\n","protected":false},"author":191432657,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"class_list":["post-53291","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bellelivingwell.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/pages\/53291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bellelivingwell.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bellelivingwell.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bellelivingwell.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/users\/191432657"}],"replies":[{"embeddable":true,"href":"https:\/\/bellelivingwell.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/comments?post=53291"}],"version-history":[{"count":3,"href":"https:\/\/bellelivingwell.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/pages\/53291\/revisions"}],"predecessor-version":[{"id":54417,"href":"https:\/\/bellelivingwell.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/pages\/53291\/revisions\/54417"}],"wp:attachment":[{"href":"https:\/\/bellelivingwell.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/media?parent=53291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}